{"id":3574,"date":"2020-01-21T14:30:09","date_gmt":"2020-01-21T13:30:09","guid":{"rendered":"https:\/\/meotec.com\/nous\/lequipe\/"},"modified":"2023-04-13T11:55:54","modified_gmt":"2023-04-13T09:55:54","slug":"squadra","status":"publish","type":"page","link":"https:\/\/meotec.com\/it\/squadra\/","title":{"rendered":"Squadra"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1602671142625 grid_section\" style=' text-align:left;'><div class=\" section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-10 vc_hidden-lg vc_hidden-md vc_hidden-sm vc_hidden-xs\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Governance<\/h2>\n\n\t\t<\/div>\n\t<\/div><div class=\"vc_empty_space\"  style=\"height: 25px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 18.75pt; background: white; vertical-align: baseline;\"><span style=\"font-size: 11.5pt; font-family: Arial, sans-serif;\">Meotec appartiene per quasi l&#8217;80% ai suoi dipendenti. Il nostro modello di Governance si basa sulla responsabilit\u00e0 del team, un libero scambio di opinioni e reattivit\u00e0 nel processo decisionale.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2 vc_hidden-lg vc_hidden-md vc_hidden-sm vc_hidden-xs\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  team-l-info grid_section\" style=' text-align:center;'><div class=\" section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-3 vc_hidden-lg vc_hidden-md vc_hidden-sm vc_col-xs-12 vc_hidden-xs vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1602671174440\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"vc_single_image-wrapper vc_box_circle  vc_box_border_grey\"><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Pr\u00e9sident-Richard-CARON.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Pr\u00e9sident - Richard CARON\" srcset=\"https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Pr\u00e9sident-Richard-CARON.jpg 400w, https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Pr\u00e9sident-Richard-CARON-300x300.jpg 300w, https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Pr\u00e9sident-Richard-CARON-150x150.jpg 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div>\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"  style=\"height: 20px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  nomcollab\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\">Richard CARON<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  nomcollab\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">Presidente<\/p>\n\n\t\t<\/div>\n\t<\/div><span class='q_social_icon_holder circle_social' ><a itemprop='url' href='https:\/\/www.linkedin.com\/in\/caronrichard\/' target='_blank'><span class='fa-stack fa-2x' style=''><i class=\"qode_icon_font_awesome fa fa-linkedin-square \" style=\"\" ><\/i><\/span><\/a><\/span><div class=\"vc_empty_space\"  style=\"height: 20px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 vc_hidden-lg vc_hidden-md vc_hidden-sm vc_col-xs-12 vc_hidden-xs vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1602671181765\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"vc_single_image-wrapper vc_box_circle  vc_box_border_grey\"><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-G\u00e9n\u00e9ral-Adjoint-Charles-VINCENT.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Directeur G\u00e9n\u00e9ral Adjoint - Charles VINCENT\" srcset=\"https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-G\u00e9n\u00e9ral-Adjoint-Charles-VINCENT.jpg 400w, https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-G\u00e9n\u00e9ral-Adjoint-Charles-VINCENT-300x300.jpg 300w, https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-G\u00e9n\u00e9ral-Adjoint-Charles-VINCENT-150x150.jpg 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div>\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"  style=\"height: 20px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  nomcollab\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\">Charles VINCENT<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  nomcollab\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">Socio<\/p>\n\n\t\t<\/div>\n\t<\/div><span class='q_social_icon_holder circle_social' ><a itemprop='url' href='https:\/\/www.linkedin.com\/in\/charles-vincent-49825013' target='_blank'><span class='fa-stack fa-2x' style=''><i class=\"qode_icon_font_awesome fa fa-linkedin-square \" style=\"\" ><\/i><\/span><\/a><\/span><div class=\"vc_empty_space\"  style=\"height: 20px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 vc_hidden-lg vc_hidden-md vc_hidden-sm vc_col-xs-12 vc_hidden-xs vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1602671188380\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"vc_single_image-wrapper vc_box_circle  vc_box_border_grey\"><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-G\u00e9n\u00e9ral-Adjoint-Thibaud-CAVELIER-DE-CUVERVILLE.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Directeur G\u00e9n\u00e9ral Adjoint - Thibaud CAVELIER DE CUVERVILLE\" srcset=\"https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-G\u00e9n\u00e9ral-Adjoint-Thibaud-CAVELIER-DE-CUVERVILLE.jpg 400w, https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-G\u00e9n\u00e9ral-Adjoint-Thibaud-CAVELIER-DE-CUVERVILLE-300x300.jpg 300w, https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-G\u00e9n\u00e9ral-Adjoint-Thibaud-CAVELIER-DE-CUVERVILLE-150x150.jpg 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div>\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"  style=\"height: 20px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  nomcollab\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\">Thibaud CAVELIER<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  nomcollab\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">Socio<\/p>\n\n\t\t<\/div>\n\t<\/div><span class='q_social_icon_holder circle_social' ><a itemprop='url' href='https:\/\/www.linkedin.com\/in\/thibaudcaveliermeotec\/' target='_blank'><span class='fa-stack fa-2x' style=''><i class=\"qode_icon_font_awesome fa fa-linkedin-square \" style=\"\" ><\/i><\/span><\/a><\/span><div class=\"vc_empty_space\"  style=\"height: 20px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 vc_hidden-lg vc_hidden-md vc_hidden-sm vc_col-xs-12 vc_hidden-xs vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1602671194442\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"vc_single_image-wrapper vc_box_circle  vc_box_border_grey\"><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-G\u00e9n\u00e9ral-Adjoint-Pascal-POUILLOUX.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Directeur G\u00e9n\u00e9ral Adjoint - Pascal POUILLOUX\" srcset=\"https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-G\u00e9n\u00e9ral-Adjoint-Pascal-POUILLOUX.jpg 400w, https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-G\u00e9n\u00e9ral-Adjoint-Pascal-POUILLOUX-300x300.jpg 300w, https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-G\u00e9n\u00e9ral-Adjoint-Pascal-POUILLOUX-150x150.jpg 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div>\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"  style=\"height: 20px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  nomcollab\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\">Pascal POUILLOUX<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  nomcollab\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">Socio<\/p>\n\n\t\t<\/div>\n\t<\/div><span class='q_social_icon_holder circle_social' ><a itemprop='url' href='https:\/\/www.linkedin.com\/in\/pascal-pouilloux-aa35b02\/' target='_blank'><span class='fa-stack fa-2x' style=''><i class=\"qode_icon_font_awesome fa fa-linkedin-square \" style=\"\" ><\/i><\/span><\/a><\/span><div class=\"vc_empty_space\"  style=\"height: 20px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  team-l-info vc_custom_1579077377198 grid_section\" style=' text-align:center;'><div class=\" section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-3 vc_hidden-lg vc_hidden-md vc_hidden-sm vc_col-xs-12 vc_hidden-xs vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1602671204928\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"vc_single_image-wrapper vc_box_circle  vc_box_border_grey\"><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-G\u00e9n\u00e9ral-Adjoint-Christophe-JACQUES-bis.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Directeur G\u00e9n\u00e9ral Adjoint - Christophe JACQUES bis\" srcset=\"https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-G\u00e9n\u00e9ral-Adjoint-Christophe-JACQUES-bis.jpg 400w, https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-G\u00e9n\u00e9ral-Adjoint-Christophe-JACQUES-bis-300x300.jpg 300w, https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-G\u00e9n\u00e9ral-Adjoint-Christophe-JACQUES-bis-150x150.jpg 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div>\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"  style=\"height: 20px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  nomcollab\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\">Christophe JACQUES<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  nomcollab\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">Socio<\/p>\n\n\t\t<\/div>\n\t<\/div><span class='q_social_icon_holder circle_social' ><a itemprop='url' href='https:\/\/www.linkedin.com\/in\/christophe-jacques-2800058\/' target='_blank'><span class='fa-stack fa-2x' style=''><i class=\"qode_icon_font_awesome fa fa-linkedin-square \" style=\"\" ><\/i><\/span><\/a><\/span><div class=\"vc_empty_space\"  style=\"height: 20px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 vc_hidden-lg vc_hidden-md vc_hidden-sm vc_col-xs-12 vc_hidden-xs vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1602671213231\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"vc_single_image-wrapper vc_box_circle  vc_box_border_grey\"><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-g\u00e9n\u00e9ral-LUCA-Arnaud-TRAGIN.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Directeur g\u00e9n\u00e9ral LUCA - Arnaud TRAGIN\" srcset=\"https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-g\u00e9n\u00e9ral-LUCA-Arnaud-TRAGIN.jpg 400w, https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-g\u00e9n\u00e9ral-LUCA-Arnaud-TRAGIN-300x300.jpg 300w, https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Directeur-g\u00e9n\u00e9ral-LUCA-Arnaud-TRAGIN-150x150.jpg 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div>\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"  style=\"height: 20px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  nomcollab\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\">Arnaud TRAGIN<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  nomcollab\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">Socio<\/p>\n\n\t\t<\/div>\n\t<\/div><span class='q_social_icon_holder circle_social' ><a itemprop='url' href='https:\/\/www.linkedin.com\/in\/arnaud-tragin-8b425987\/' target='_blank'><span class='fa-stack fa-2x' style=''><i class=\"qode_icon_font_awesome fa fa-linkedin-square \" style=\"\" ><\/i><\/span><\/a><\/span><div class=\"vc_empty_space\"  style=\"height: 20px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 vc_hidden-lg vc_hidden-md vc_hidden-sm vc_col-xs-12 vc_hidden-xs vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1602671227380\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"vc_single_image-wrapper vc_box_circle  vc_box_border_grey\"><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Dir.-d\u00e9veloppement-RH-St\u00e9phane-GRENAT.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Dir. d\u00e9veloppement RH - St\u00e9phane GRENAT\" srcset=\"https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Dir.-d\u00e9veloppement-RH-St\u00e9phane-GRENAT.jpg 400w, https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Dir.-d\u00e9veloppement-RH-St\u00e9phane-GRENAT-300x300.jpg 300w, https:\/\/meotec.com\/wp-content\/uploads\/2019\/12\/Dir.-d\u00e9veloppement-RH-St\u00e9phane-GRENAT-150x150.jpg 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div>\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"  style=\"height: 20px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  nomcollab\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\">St\u00e9phane GRENAT<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  nomcollab\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">Socio<\/p>\n\n\t\t<\/div>\n\t<\/div><span class='q_social_icon_holder circle_social' ><a itemprop='url' href='https:\/\/www.linkedin.com\/in\/stephane-grenat-a1b98127\/' target='_blank'><span class='fa-stack fa-2x' style=''><i class=\"qode_icon_font_awesome fa fa-linkedin-square \" style=\"\" ><\/i><\/span><\/a><\/span><div class=\"vc_empty_space\"  style=\"height: 20px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3 vc_hidden-lg vc_hidden-md vc_hidden-sm vc_col-xs-12 vc_hidden-xs vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1602671237655\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"vc_single_image-wrapper vc_box_circle  vc_box_border_grey\"><img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/meotec.com\/wp-content\/uploads\/2020\/01\/brechet-david.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"brechet david\" srcset=\"https:\/\/meotec.com\/wp-content\/uploads\/2020\/01\/brechet-david.jpg 400w, https:\/\/meotec.com\/wp-content\/uploads\/2020\/01\/brechet-david-300x300.jpg 300w, https:\/\/meotec.com\/wp-content\/uploads\/2020\/01\/brechet-david-150x150.jpg 150w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/div>\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"  style=\"height: 20px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  nomcollab\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 style=\"text-align: center;\">David BRECHET<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"wpb_text_column wpb_content_element  nomcollab\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center;\">Socio<\/p>\n\n\t\t<\/div>\n\t<\/div><span class='q_social_icon_holder circle_social' ><a itemprop='url' href='https:\/\/www.linkedin.com\/in\/davidbrechet\/' target='_blank'><span class='fa-stack fa-2x' style=''><i class=\"qode_icon_font_awesome fa fa-linkedin-square \" style=\"\" ><\/i><\/span><\/a><\/span><div class=\"vc_empty_space\"  style=\"height: 20px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1602671267717 grid_section\" style=' text-align:left;'><div class=\" section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-10\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Mandato<\/h2>\n\n\t\t<\/div>\n\t<\/div><div class=\"vc_empty_space\"  style=\"height: 25px\" >\n\t<span class=\"vc_empty_space_inner\">\n\t\t<span class=\"empty_space_image\"  ><\/span>\n\t<\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"margin: 0cm; margin-bottom: .0001pt; line-height: 18.75pt; background: white; vertical-align: baseline;\"><span style=\"font-size: 11.5pt; font-family: Arial, sans-serif;\">Decisamente imprenditoriale, MEOTEC facilita lo sviluppo delle competenze dei suoi consulenti e collaboratori, incoraggia l&#8217;assunzione di iniziative e promuove l&#8217;assunzione di responsabilit\u00e0 in ambienti stimolanti, sempre diversi e all&#8217;interno di settori in profonda trasformazione.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid  vc_custom_1580394773006 grid_section\" style=' text-align:left;'><div class=\" section_inner clearfix\"><div class='section_inner_margin clearfix'><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" width=\"2560\" height=\"1256\" src=\"https:\/\/meotec.com\/wp-content\/uploads\/2020\/09\/mosaique-rectangle-V-fin-julia-modifi\u00e9-scaled.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"mosaique rectangle V fin julia modifi\u00e9\" srcset=\"https:\/\/meotec.com\/wp-content\/uploads\/2020\/09\/mosaique-rectangle-V-fin-julia-modifi\u00e9-scaled.jpg 2560w, https:\/\/meotec.com\/wp-content\/uploads\/2020\/09\/mosaique-rectangle-V-fin-julia-modifi\u00e9-300x147.jpg 300w, https:\/\/meotec.com\/wp-content\/uploads\/2020\/09\/mosaique-rectangle-V-fin-julia-modifi\u00e9-1024x503.jpg 1024w, https:\/\/meotec.com\/wp-content\/uploads\/2020\/09\/mosaique-rectangle-V-fin-julia-modifi\u00e9-768x377.jpg 768w, https:\/\/meotec.com\/wp-content\/uploads\/2020\/09\/mosaique-rectangle-V-fin-julia-modifi\u00e9-1536x754.jpg 1536w, https:\/\/meotec.com\/wp-content\/uploads\/2020\/09\/mosaique-rectangle-V-fin-julia-modifi\u00e9-2048x1005.jpg 2048w, https:\/\/meotec.com\/wp-content\/uploads\/2020\/09\/mosaique-rectangle-V-fin-julia-modifi\u00e9-700x344.jpg 700w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div      class=\"vc_row wpb_row section vc_row-fluid \" style=' text-align:left;'><div class=\" full_section_inner clearfix\"><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1574694885082\"><div class=\"wpb_wrapper\"><div class=\"qode-advanced-call-to-action\" style=\"height:155px\">\n\t<a class=\"advanced-cta-link\" href=\"#candidati\" target=\"_self\"><\/a>\n\t<div class=\"qode-advanced-cta-content\">\t\t\n\t    <span class=\"qode-advanced-cta-text-holder\" style=\"color:#f7a824;font-size:25px;font-weight:700\">\n\t\t    Candidati in MEOTEC\t    <\/span>\n\t    <span class=\"qode-advanced-cta-icon-holder\" style=\"color:#f7a824;font-size:38px;font-weight:600;height:45px;width:45px\">\n\t\t    <span class=\"qode-advanced-cta-icon-holder-table\">\n\t\t    \t<span class=\"qode-advanced-cta-icon-holder-cell\" >\n\t\t\t    \t<span aria-hidden=\"true\" class=\"qode_icon_font_elegant arrow_right qode-advanced-cta-icon\" ><\/span>\t\t\t    <\/span>\n\t\t    <\/span>\n\t\t    \t    <\/span>\n\t<\/div>\n\t\t\t<div class=\"qode-advanced-cta-background-holder\">\n\t\t\t<span class=\"qode-advanced-cta-background-1 qode-type1-gradient-left-to-right\"><\/span>\n\t\t\t<span class=\"qode-advanced-cta-background-2 qode-type1-gradient-left-to-right\"><\/span>\n\t\t\t<span class=\"qode-advanced-cta-background-3\"><\/span>\n\t\t<\/div>\n\t<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6 vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1508857534874\"><div class=\"wpb_wrapper\"><div class=\"qode-advanced-call-to-action\" style=\"height:155px\">\n\t<a class=\"advanced-cta-link\" href=\"https:\/\/meotec.com\/it\/contact\/\" target=\"_self\"><\/a>\n\t<div class=\"qode-advanced-cta-content\">\t\t\n\t    <span class=\"qode-advanced-cta-text-holder\" style=\"color:#ffffff;font-size:25px;font-weight:700\">\n\t\t    Contattaci\t    <\/span>\n\t    <span class=\"qode-advanced-cta-icon-holder\" style=\"color:#ffffff;font-size:38px;font-weight:600;height:45px;width:45px\">\n\t\t    <span class=\"qode-advanced-cta-icon-holder-table\">\n\t\t    \t<span class=\"qode-advanced-cta-icon-holder-cell\" >\n\t\t\t    \t<span aria-hidden=\"true\" class=\"qode_icon_font_elegant arrow_right qode-advanced-cta-icon\" ><\/span>\t\t\t    <\/span>\n\t\t    <\/span>\n\t\t    \t    <\/span>\n\t<\/div>\n\t\t\t<div class=\"qode-advanced-cta-background-holder\">\n\t\t\t<span class=\"qode-advanced-cta-background-1 qode-type1-gradient-left-to-right\"><\/span>\n\t\t\t<span class=\"qode-advanced-cta-background-2 qode-type1-gradient-left-to-right\"><\/span>\n\t\t\t<span class=\"qode-advanced-cta-background-3\"><\/span>\n\t\t<\/div>\n\t<\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Governance Meotec appartiene per quasi l'80% ai suoi dipendenti. Il nostro modello di Governance si basa sulla responsabilit\u00e0 del team,...","protected":false},"author":26,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"Il team - MEOTEC - Societ\u00e0 di consulenza operativa","_seopress_titles_desc":"Meotec \u00e8 un team di dipendenti affiatati, appassionati e ricco di progetti. Meotec appartiene per quasi l&#039;80% ai suoi dipendenti.","_seopress_robots_index":"","footnotes":""},"class_list":["post-3574","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/meotec.com\/it\/wp-json\/wp\/v2\/pages\/3574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/meotec.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/meotec.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/meotec.com\/it\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/meotec.com\/it\/wp-json\/wp\/v2\/comments?post=3574"}],"version-history":[{"count":0,"href":"https:\/\/meotec.com\/it\/wp-json\/wp\/v2\/pages\/3574\/revisions"}],"wp:attachment":[{"href":"https:\/\/meotec.com\/it\/wp-json\/wp\/v2\/media?parent=3574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}